{"id":1522,"date":"2023-01-31T15:05:11","date_gmt":"2023-01-31T14:05:11","guid":{"rendered":"https:\/\/www.querinistampalia.org\/?page_id=1522"},"modified":"2026-04-16T10:08:11","modified_gmt":"2026-04-16T08:08:11","slug":"biblioteca","status":"publish","type":"page","link":"https:\/\/fquerini.fabricandum.com\/it\/biblioteca\/","title":{"rendered":"Biblioteca"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1522\" class=\"elementor elementor-1522\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f04ae4 elementor-section-height-min-height elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-items-middle\" data-id=\"7f04ae4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c6aff84\" data-id=\"c6aff84\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e0b0aeb hero_second_column contrastable boxTextContrastable\" data-id=\"e0b0aeb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0ae39a elementor-widget elementor-widget-heading\" data-id=\"f0ae39a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">La Biblioteca della Querini<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-867d4b2 biblioteca elementor-widget elementor-widget-text-editor\" data-id=\"867d4b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;La formazione \u00e8 il nostro investimento&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:17347,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:16711935},&quot;9&quot;:0,&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0,&quot;17&quot;:0}\">La formazione \u00e8 il nostro investimento<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8826f68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8826f68\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f17f5e1\" data-id=\"f17f5e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84991ea biblioteca elementor-widget elementor-widget-text-editor\" data-id=\"84991ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Biblioteca \u00e8 di carattere generale, conserva e mette a disposizione circa 400.000 volumi, tra opere antiche e libri moderni, ed \u00e8 considerata, da pi\u00f9 di 150 anni, la &#8216;biblioteca dei veneziani&#8217;. Aperta anche nei giorni festivi, vi possono accedere gratuitamente tutti coloro che hanno compiuto 16 anni; nelle sale di lettura si possono consultare circa 20.000 volumi, avere a disposizione pi\u00f9 di 200 riviste e periodici e sfogliare ogni giorno quotidiani locali e nazionali.<\/p><p>Un accordo con il Comune di Venezia la definisce dalla fine degli anni Settanta come &#8216;Biblioteca civica del centro storico&#8217;, riconoscendole il ruolo svolto al servizio della citt\u00e0.<\/p><p>La Biblioteca nasce nel 1869, quando viene istituita la Fondazione e il conte Giovanni stabilisce per testamento che la biblioteca di famiglia diventi d\u2019uso pubblico. Al nucleo antico di propriet\u00e0 dei Querini Stampalia si sono aggiunte a partire da allora le acquisizioni correnti e le donazioni di quanti hanno voluto rendere disponibili a lettori e studiosi le proprie biblioteche personali, o parti di esse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5daaad5 elementor-widget elementor-widget-heading\" data-id=\"5daaad5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le risorse della Biblioteca<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f8e270 biblioteca elementor-widget elementor-widget-text-editor\" data-id=\"3f8e270\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ad oggi il patrimonio documentario \u00e8 costituito da circa 400.000 volumi, 120 buste dell\u2019Archivio della famiglia Querini Stampalia, 1.300 manoscritti, 100 incunaboli, 1.617 cinquecentine, 20.250 edizioni dal XVII al XIX secolo, 20.000 opuscoli, 3.269 bandi della Repubblica di Venezia (disponibili anche in versione digitale), 4.000 periodici, di cui oltre 200 correnti, 3.000 incisioni sciolte, 355 carte geografiche e mappali antichi. <br \/><br \/>Nell\u2019Opac del Polo SBN Venezia si trovano le pubblicazioni acquisite dopo il 1990, ma anche parte del patrimonio bibliografico precedente. <br \/><br \/>Oltre 840 manoscritti sui quasi 1.300 posseduti dalla Biblioteca sono stati inseriti nel catalogo regionale Nuova Biblioteca Manoscritta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eb34673 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb34673\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b1d0f7\" data-id=\"6b1d0f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1cf691 elementor-widget elementor-widget-html\" data-id=\"e1cf691\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/polovea.sebina.it\/SebinaOpac\/.do\" class=\"arrow-btn arrow-btn-black\" rel=\"noopener\">\n\t\tOpac del Polo SBN Venezia <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewBox=\"0 0 34 34\" fill=\"none\"><circle cx=\"17\" cy=\"17\" r=\"17\" fill=\"#000\"><\/circle><path d=\"M25.8536 17.3536C26.0488 17.1583 26.0488 16.8417 25.8536 16.6464L22.6716 13.4645C22.4763 13.2692 22.1597 13.2692 21.9645 13.4645C21.7692 13.6597 21.7692 13.9763 21.9645 14.1716L24.7929 17L21.9645 19.8284C21.7692 20.0237 21.7692 20.3403 21.9645 20.5355C22.1597 20.7308 22.4763 20.7308 22.6716 20.5355L25.8536 17.3536ZM8.5 17.5L25.5 17.5V16.5L8.5 16.5V17.5Z\" fill=\"white\"><\/path><\/svg>\n\t\t\t<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c736613\" data-id=\"c736613\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50a2d0d elementor-widget elementor-widget-html\" data-id=\"50a2d0d\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/www.nuovabibliotecamanoscritta.it\/FQSVe.html\" class=\"arrow-btn arrow-btn-black\" rel=\"noopener\">\n\t\tNuova Biblioteca Manoscritta <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewBox=\"0 0 34 34\" fill=\"none\"><circle cx=\"17\" cy=\"17\" r=\"17\" fill=\"#000\"><\/circle><path d=\"M25.8536 17.3536C26.0488 17.1583 26.0488 16.8417 25.8536 16.6464L22.6716 13.4645C22.4763 13.2692 22.1597 13.2692 21.9645 13.4645C21.7692 13.6597 21.7692 13.9763 21.9645 14.1716L24.7929 17L21.9645 19.8284C21.7692 20.0237 21.7692 20.3403 21.9645 20.5355C22.1597 20.7308 22.4763 20.7308 22.6716 20.5355L25.8536 17.3536ZM8.5 17.5L25.5 17.5V16.5L8.5 16.5V17.5Z\" fill=\"white\"><\/path><\/svg>\n\t\t\t<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5abed2 elementor-widget elementor-widget-heading\" data-id=\"b5abed2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Cataloghi cartacei<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed38cf0 biblioteca elementor-widget elementor-widget-text-editor\" data-id=\"ed38cf0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Biblioteca dispone inoltre di cataloghi cartacei a schede e a volumi per le opere acquisite prima del 1990. <br \/>Per qualsiasi informazione: <a href=\"mailto:biblioteca@querinistampalia.org\">biblioteca@querinistampalia.org<\/a>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58dea73 golden-section contrastable elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58dea73\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-552ee8f\" data-id=\"552ee8f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c17dcfc biblioteca elementor-widget elementor-widget-heading\" data-id=\"c17dcfc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Orari<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00d62ff elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"00d62ff\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da86361 elementor-widget elementor-widget-text-editor\" data-id=\"da86361\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Biblioteca ed Emeroteca\\nda marted\u00ec a venerd\u00ec 10\/20\\nsabato, domenica e festivi 10\/19\\nluned\u00ec chiuso&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:963,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:16711935},&quot;9&quot;:0,&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\"><strong>Biblioteca ed Emeroteca<\/strong><br \/>da marted\u00ec a venerd\u00ec <span style=\"text-decoration: underline;\">10:00-20:00<\/span><br \/>sabato, domenica e festivi <span style=\"text-decoration: underline;\">10:00-19:00<\/span><br \/>luned\u00ec chiuso<\/span><\/p><p><strong>Aperture straordinarie<\/strong><br \/>La Biblioteca \u00e8 aperta anche nei seguenti giorni: <br \/>Sabato Santo, 2 giugno, vigilia del Redentore, 1 e 21 novembre, 8, 24, 26 e 31 dicembre<\/p><p><strong>Chiusure straordinarie<\/strong><br \/><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;La Biblioteca \u00e8 chiusa anche nei seguenti giorni 1 gennaio, Pasqua, Luned\u00ec dell'Angelo, 25 aprile, 1 maggio, 15 agosto, 25 dicembre&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:7107,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:16711935},&quot;9&quot;:0,&quot;10&quot;:0,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:2,&quot;2&quot;:0},&quot;15&quot;:&quot;Arial&quot;}\">La Biblioteca \u00e8 chiusa anche nei seguenti giorni:<br \/>1 gennaio, Pasqua, Luned\u00ec dell&#8217;Angelo, 25 aprile, 1 maggio, 15 agosto, 25 dicembre<\/span><\/p><p><strong>Orari del servizio di distribuzione<\/strong><br \/><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;da marted\u00ec a venerd\u00ec 10\/19.30 \\nsabato, domenica e festivi10\/18.30 \\nLa consultazione dei periodici conservati nei depositi esterni va programmata su appuntamento scrivendo a biblioteca@querinistampalia.org&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:7107,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:16711935},&quot;9&quot;:0,&quot;10&quot;:0,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:2,&quot;2&quot;:0},&quot;15&quot;:&quot;Arial&quot;}\">da marted\u00ec a venerd\u00ec 10:00-19:30<br \/>sabato, domenica e festivi 10:00-18:30<br \/>La consultazione dei materiali antichi e di pregio, dei quotidiani di grande formato e dei periodici conservati nei depositi esterni va programmata su appuntamento scrivendo a <a href=\"mailto:biblioteca@querinistampalia.org\">biblioteca@querinistampalia.org<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-83808d0\" data-id=\"83808d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0466ac8 biblioteca elementor-widget elementor-widget-heading\" data-id=\"0466ac8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Informazioni<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b98ec0a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b98ec0a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f95bb6 elementor-widget elementor-widget-text-editor\" data-id=\"9f95bb6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;La Biblioteca \u00e8 aperta ai lettori maggiori di 16 anni. Si accede con tessera, che si ottiene tramite iscrizione gratuita.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:931,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:16711935},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:10066329}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\">La Biblioteca \u00e8 aperta ai lettori maggiori di 16 anni.<br \/>Si accede con tessera, che si ottiene tramite iscrizione gratuita.<\/span><\/p><p><strong>Come iscriversi<br \/><\/strong>La richiesta va inoltrata a <a href=\"mailto:biblioteca@querinistampalia.org\">biblioteca@querinistampalia.org<\/a> allegando il modulo di iscrizione, compilato e firmato su entrambi i fogli, insieme alla scansione di un documento d&#8217;identit\u00e0 valido.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-223dabd elementor-widget elementor-widget-html\" data-id=\"223dabd\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/fquerini.fabricandum.com\/wp-content\/uploads\/2024\/06\/Biblioteca-ITA.pdf\" class=\"arrow-btn arrow-btn-black\">\n\t\tscarica il modulo <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewBox=\"0 0 34 34\" fill=\"none\"><circle cx=\"17\" cy=\"17\" r=\"17\" fill=\"#000\"><\/circle><path d=\"M25.8536 17.3536C26.0488 17.1583 26.0488 16.8417 25.8536 16.6464L22.6716 13.4645C22.4763 13.2692 22.1597 13.2692 21.9645 13.4645C21.7692 13.6597 21.7692 13.9763 21.9645 14.1716L24.7929 17L21.9645 19.8284C21.7692 20.0237 21.7692 20.3403 21.9645 20.5355C22.1597 20.7308 22.4763 20.7308 22.6716 20.5355L25.8536 17.3536ZM8.5 17.5L25.5 17.5V16.5L8.5 16.5V17.5Z\" fill=\"white\"><\/path><\/svg>\n\t\t\t<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-600b656 elementor-widget elementor-widget-text-editor\" data-id=\"600b656\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\"><strong>Accoglienza e accessibilit\u00e0<br \/><\/strong><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;La Biblioteca \u00e8 al primo piano del palazzo, raggiungibile anche con ascensore. &quot;}\" data-sheets-userformat=\"{&quot;2&quot;:963,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:16711935},&quot;9&quot;:0,&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\">La Biblioteca \u00e8 al primo piano del palazzo, raggiungibile anche con ascensore. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a6279d elementor-widget elementor-widget-text-editor\" data-id=\"9a6279d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\"><strong>Regolamento della Biblioteca<br \/><\/strong><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;La Biblioteca \u00e8 al primo piano del palazzo, raggiungibile anche con ascensore. &quot;}\" data-sheets-userformat=\"{&quot;2&quot;:963,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:16711935},&quot;9&quot;:0,&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\">Informazioni generali, sull\u2019accesso e sui servizi.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5940ef8 elementor-widget elementor-widget-html\" data-id=\"5940ef8\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/fquerini.fabricandum.com\/wp-content\/uploads\/2024\/04\/Q24-Biblioteca-ITA-Regolamento-1.pdf\" class=\"arrow-btn arrow-btn-black\">\n\t\tscarica il regolamento <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewBox=\"0 0 34 34\" fill=\"none\"><circle cx=\"17\" cy=\"17\" r=\"17\" fill=\"#000\"><\/circle><path d=\"M25.8536 17.3536C26.0488 17.1583 26.0488 16.8417 25.8536 16.6464L22.6716 13.4645C22.4763 13.2692 22.1597 13.2692 21.9645 13.4645C21.7692 13.6597 21.7692 13.9763 21.9645 14.1716L24.7929 17L21.9645 19.8284C21.7692 20.0237 21.7692 20.3403 21.9645 20.5355C22.1597 20.7308 22.4763 20.7308 22.6716 20.5355L25.8536 17.3536ZM8.5 17.5L25.5 17.5V16.5L8.5 16.5V17.5Z\" fill=\"white\"><\/path><\/svg>\n\t\t\t<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5291bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5291bf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c2e78d\" data-id=\"0c2e78d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-149463c biblioteca elementor-widget elementor-widget-heading\" data-id=\"149463c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Servizi<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd093a9 biblioteca elementor-widget elementor-widget-text-editor\" data-id=\"fd093a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Per usufruire al meglio di quanto \u00e8 conservato in Biblioteca sono a disposizione diversi servizi, alcuni di questi attivabili anche online. L'accesso a Internet attraverso la rete WiFi \u00e8 disponibile gratuitamente.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:963,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:16711935},&quot;9&quot;:0,&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\">Per usufruire al meglio di quanto \u00e8 conservato in Biblioteca sono a disposizione diversi servizi, alcuni di questi attivabili anche online.<br \/>L&#8217;accesso a Internet attraverso la rete WiFi \u00e8 disponibile gratuitamente.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-add7787 toggle_custom_ml elementor-widget elementor-widget-toggle\" data-id=\"add7787\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1821\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1821\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><circle cx=\"23\" cy=\"23\" r=\"23\" transform=\"rotate(90 23 23)\" fill=\"#272727\"><\/circle><path d=\"M30 19L22.5 28L15 19\" stroke=\"#BD995C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><circle cx=\"23\" cy=\"23\" r=\"23\" transform=\"rotate(90 23 23)\" fill=\"#272727\"><\/circle><path d=\"M30 19L22.5 28L15 19\" stroke=\"#BD995C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"><h4>Sale di consultazione<\/h4> <br><span>Leggi di pi\u00f9 <\/span><\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1821\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1821\"><p>Le sale della Biblioteca ne rispecchiano la storia: accanto a quelle di fine Ottocento, con stucchi e arredi d\u2019epoca e sui tavoli le lampade disegnate da Carlo Scarpa, si trovano le sale pi\u00f9 moderne rivisitate da Mario Botta.<\/p><p>Sugli scaffali le opere in consultazione sono organizzate per aree disciplinari secondo la Classificazione Decimale Dewey:<\/p><ul><li>000 Biblioteconomia, bibliografia, museologia<\/li><li>100 Filosofia e psicologia<\/li><li>200 Religione<\/li><li>300 Scienze sociali<\/li><li>400 Linguaggio 500 Scienza<\/li><li>600 Tecnologia<\/li><li>700 Arti e attivit\u00e0 ricreative<\/li><li>800 Letteratura<\/li><li>900 Storia e geografia<\/li><\/ul><p><br \/>Tre sale sono dedicate rispettivamente: ai repertori per lo studio dei materiali rari e di pregio (REPERTORI), ai dizionari linguistici (CONS.DIZ.) e alla materia veneta (CONS.VEN.). Una sala \u00e8 riservata alla consultazione su prenotazione dei periodici di grande formato e dei libri antichi.<br \/>L\u2019emeroteca ospita l&#8217;annata in corso di circa 200 periodici correnti, in lingua italiana, inglese e francese, ordinati alfabeticamente secondo il titolo, insieme al numero del giorno dei quotidiani locali e nazionali.<\/p><p>I volumi possono essere prelevati direttamente dai lettori e dopo la consultazione vanno lasciati sugli appositi carrelli rossi. Tutti gli altri materiali, conservati nei depositi librari, vanno richiesti al bancone della distribuzione (vedi Lettura in sede).<\/p><p>I tavoli sono dotati di prese elettriche e la connessione WiFi \u00e8 disponibile gratuitamente. Postazioni in piedi sono disponibili per la consultazione dei cataloghi in linea.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1822\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1822\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><circle cx=\"23\" cy=\"23\" r=\"23\" transform=\"rotate(90 23 23)\" fill=\"#272727\"><\/circle><path d=\"M30 19L22.5 28L15 19\" stroke=\"#BD995C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><circle cx=\"23\" cy=\"23\" r=\"23\" transform=\"rotate(90 23 23)\" fill=\"#272727\"><\/circle><path d=\"M30 19L22.5 28L15 19\" stroke=\"#BD995C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"><h4>Lettura in sede<\/h4> <br><span>Leggi di pi\u00f9 <\/span><\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1822\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1822\"><p>La maggior parte dei volumi conservati nei depositi librari in sede pu\u00f2 essere richiesta al momento al banco della distribuzione, mentre periodici e materiali antichi devono essere prenotati via mail all&#8217;indirizzo: <a href=\"mailto:biblioteca@querinistampalia.org\">biblioteca@querinistampalia.org<\/a>.<\/p><ul><li>I materiali antichi e di pregio (collocazioni che iniziano con MSS. AUTOGR., BANCO, C. GEOGR., INC., OPUS., PIANO I, PER. D-G o indicati come riservati RIS., i volumi appartenenti alla Collezione Intesa Sanpaolo recanti la segnatura CARIVE) vanno prenotati anticipatamente via e-mail e saranno consegnati un pezzo alla volta, richiedendo all&#8217;utente il deposito di un documento di identificazione. Tali materiali potranno essere consultati esclusivamente nell\u2019apposita sala vicina alla distribuzione. In caso di precario stato di conservazione dei materiali, la consultazione potr\u00e0 essere sospesa. Se presenti riproduzioni fotografiche o facsimilari (in particolare incisioni e carte geografiche), la consultazione delle copie \u00e8 prioritaria rispetto alla consultazione degli originali, che verranno consegnati solo in caso di motivate esigenze di studio.<\/li><li>I periodici di grande formato con collocazione PER.A, fra cui i quotidiani rilegati, devono essere richiesti anticipatamente via e-mail e verranno distribuiti nel numero massimo di 3 volumi al giorno per richiedente.<\/li><li>La maggior parte dei periodici contrassegnati dalle collocazioni PER.B e PER.C. si trova in depositi esterni. La consultazione va pertanto prenotata anticipatamente in distribuzione oppure via e-mail.<\/li><\/ul><p><br \/>NB: Tutti i volumi ricevuti dovranno essere riconsegnati prima di uscire dalla Fondazione. Nel caso si intenda proseguire la consultazione di una o pi\u00f9 pubblicazioni moderne nei giorni successivi o in un secondo momento, si consiglia di segnalarlo alla distribuzione.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1823\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1823\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><circle cx=\"23\" cy=\"23\" r=\"23\" transform=\"rotate(90 23 23)\" fill=\"#272727\"><\/circle><path d=\"M30 19L22.5 28L15 19\" stroke=\"#BD995C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><circle cx=\"23\" cy=\"23\" r=\"23\" transform=\"rotate(90 23 23)\" fill=\"#272727\"><\/circle><path d=\"M30 19L22.5 28L15 19\" stroke=\"#BD995C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"><h4>Informazioni bibliografiche<\/h4> <br><span>Leggi di pi\u00f9 <\/span><\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1823\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1823\"><p>Scopo di questo servizio \u00e8 assistere il lettore nella ricerca bibliografica, fornendo orientamenti e indicazioni utili alla consultazione di cataloghi e repertori cartacei e in linea, all\u2019accesso ai documenti posseduti dalla Biblioteca e al recupero di informazioni presenti in Internet. <br \/><br \/>Il servizio di informazioni bibliografiche non intende sostituire l&#8217;utente nel suo lavoro, ma offrirgli un supporto per la messa a punto dei percorsi di ricerca e la miglior utilizzazione del patrimonio e dei servizi della Biblioteca. <br \/><br \/>Oltre che in sede, il servizio \u00e8 attivo anche per gli utenti fuori sede limitatamente alla localizzazione di libri e periodici posseduti dalla Biblioteca, al controllo di dati bibliografici, all\u2019identificazione di fonti e strumenti bibliografici a carattere orientativo. <br \/><br \/>\u00c8 esclusa in ogni caso dal servizio la redazione di bibliografie generali ed analitiche.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1824\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1824\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><circle cx=\"23\" cy=\"23\" r=\"23\" transform=\"rotate(90 23 23)\" fill=\"#272727\"><\/circle><path d=\"M30 19L22.5 28L15 19\" stroke=\"#BD995C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><circle cx=\"23\" cy=\"23\" r=\"23\" transform=\"rotate(90 23 23)\" fill=\"#272727\"><\/circle><path d=\"M30 19L22.5 28L15 19\" stroke=\"#BD995C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"><h4>Prestito<\/h4> <br><span>Leggi di pi\u00f9 <\/span><\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1824\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1824\"><p>Una parte dei materiali moderni \u00e8 disponibile per il prestito personale da parte degli utenti iscritti alla Biblioteca e residenti in Veneto. <br \/>Sono concessi a prestito fino ad un massimo di tre volumi per ciascun lettore, per la durata di un mese, ed \u00e8 ammesso il rinnovo purch\u00e9 in assenza di prenotazioni da parte di altri utenti.<\/p><p>I volumi ammessi al prestito possono essere richiesti al bancone della distribuzione, oppure prenotati via mail o attraverso il portale dell&#8217;OPAC SBN.<\/p><p>\u00c8 attivo il prestito interbibliotecario, a cui accedono tutte le biblioteche, che possono inoltrare le loro richieste via e-mail. \u00c8 prevista la partecipazione della biblioteca richiedente alle spese di spedizione e di segreteria; particolari agevolazioni sono previste per la Rete Biblioteche del Comune di Venezia.<\/p><p>NB: Sono in ogni caso esclusi dal prestito i periodici, i volumi collocati nelle sale di consultazione a scaffale aperto, quelli stampati da pi\u00f9 di 50 anni, le biblioteche di persona, alcune collocazioni particolari quali IST., MISC., Z, XZ, ecc. e comunque tutti i materiali di difficile reperibilit\u00e0 o in precario stato di conservazione.<\/p><p>Da luglio 2012 la Biblioteca ha aperto un punto di prestito nel supermercato dell\u2019Isola di Sant\u2019Erasmo grazie alla collaborazione con l&#8217;Associazione Archeoclub d&#8217;Italia, sede di Venezia, e il Supermercato Vignotto. Questa iniziativa tiene conto delle particolari caratteristiche del luogo, il cosiddetto \u2018orto di Venezia\u2019: un\u2019isola della laguna nord di quasi 700 abitanti dalle rinomate coltivazioni, su cui per\u00f2 non sono presenti n\u00e9 una biblioteca n\u00e9 un&#8217;edicola<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1825\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1825\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><circle cx=\"23\" cy=\"23\" r=\"23\" transform=\"rotate(90 23 23)\" fill=\"#272727\"><\/circle><path d=\"M30 19L22.5 28L15 19\" stroke=\"#BD995C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><circle cx=\"23\" cy=\"23\" r=\"23\" transform=\"rotate(90 23 23)\" fill=\"#272727\"><\/circle><path d=\"M30 19L22.5 28L15 19\" stroke=\"#BD995C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"><h4>Riproduzioni<\/h4> <br><span>Leggi di pi\u00f9 <\/span><\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1825\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1825\"><p>Il servizio di fotocopiatura o scansione \u00e8 limitato alle pubblicazioni possedute dalla Biblioteca e riservato all\u2019uso personale dei lettori, nel rispetto della normativa vigente sul diritto d\u2019autore. <br \/>Il servizio \u00e8 soggetto a tariffazione.<\/p><p>Per garantire la tutela dei materiali, sono escluse dalla fotocopiatura o scansione le pubblicazioni antecedenti al 1950 e i materiali rilegati di grande formato (per es. quotidiani) o in precario stato di conservazione. Per questi materiali pu\u00f2 essere richiesta la ripresa fotografica ove le condizioni dell&#8217;originale lo permettano.<\/p><p>Il pubblico effettua direttamente le copie utilizzando le attrezzature messe a disposizione presso la Distribuzione e seguendo le indicazioni dei bibliotecari. Nell\u2019esecuzione di copie ogni utente \u00e8 personalmente responsabile della conservazione dei materiali bibliografici e dell\u2019uso delle attrezzature.<\/p><p>Per gli utenti che non possono recarsi in Biblioteca \u00e8 disponibile il servizio di document delivery di copia digitale dei materiali richiesti. Le copie saranno eseguite nel rispetto della normativa vigente sul diritto d&#8217;autore e comunque fino ad un massimo di 50 pagine. <br \/>Il servizio \u00e8 soggetto a tariffazione.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c68fafc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c68fafc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e08ffc4\" data-id=\"e08ffc4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93a2fd5 elementor-widget elementor-widget-TwoColumnRowContent\" data-id=\"93a2fd5\" data-element_type=\"widget\" data-widget_type=\"TwoColumnRowContent.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t\t\r\n  \r\n\t\r\n<div class=\"boxlayout\" style=\"\">\r\n    <div class=\"boxlayout__column boxlayout__columntext flex-2\">\r\n        <h3 class=\"boxlayout__column--title\">Le nostre proposte di lettura<\/h3>\r\n\t\t\r\n\t\t\t\t\t\r\n        <!-- <p class='boxlayout__column--text'> -->\r\n\t\t<p>Bibliografie selezionate periodicamente per approfondire tematiche di attualit\u00e0 o legate agli eventi realizzati dalla Fondazione, per scoprire lati inaspettati di Venezia, per leggere le opere candidate ai pi\u00f9 importanti premi letterari. Le proposte sono disponibili in Biblioteca e anche consultabili online<\/p>\t\t<!-- <\/p> -->\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t        <a href=\"https:\/\/fquerini.fabricandum.com\/it\/proposte-di-lettura\/\" target=\"_self\" class=\"boxlayout__column--button\">Scopri di pi\u00f9\t\t <!-- <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewBox=\"0 0 34 34\" fill=\"none\">\r\n\t\t\t<circle cx=\"17\" cy=\"17\" r=\"17\" fill=\"#BD995C\"><\/circle>\r\n\t\t <path d=\"M25.8536 17.3536C26.0488 17.1583 26.0488 16.8417 25.8536 16.6464L22.6716 13.4645C22.4763 \r\n\t\t 13.2692 22.1597 13.2692 21.9645 13.4645C21.7692 13.6597 21.7692 13.9763 21.9645 14.1716L24.7929 \r\n\t\t 17L21.9645 19.8284C21.7692 20.0237 21.7692 20.3403 21.9645 20.5355C22.1597 20.7308 22.4763 20.7308 \r\n\t\t 22.6716 20.5355L25.8536 17.3536ZM8.5 17.5L25.5 17.5V16.5L8.5 16.5V17.5Z\" fill=\"white\"><\/path>\r\n\t\t<\/svg> -->\r\n\t\t<\/a>\r\n\t\t    <\/div>\r\n    <div class=\"boxlayout__column boxlayout__columngallery flex-1\">\r\n        <div class=\"swiper swiper6a04920a95a49\">\r\n          <!-- Additional required wrapper -->\r\n          <div class=\"swiper-wrapper\">\r\n            <!-- Slides -->\r\n\r\n\t\t\t            <div class=\"swiper-slide\">\r\n\t\t\r\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fquerini.fabricandum.com\/wp-content\/uploads\/2023\/01\/Le-nostre-proposte-di-lettura.jpg\">\r\n\t\t\t<\/div>\r\n\r\n\t\t\t          \r\n          <\/div>\r\n    \r\n          <!-- If we need navigation buttons -->\r\n          <div class=\"swiper-button-prev\"><\/div>\r\n          <div class=\"swiper-button-next\"><\/div>\r\n    \r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n\r\n\r\n  \r\n\t\r\n<div class=\"boxlayout\" style=\"flex-direction: row-reverse;\">\r\n    <div class=\"boxlayout__column boxlayout__columntext flex-2\">\r\n        <h3 class=\"boxlayout__column--title\">I gruppi di lettura<\/h3>\r\n\t\t\r\n\t\t\t\t\t\r\n        <!-- <p class='boxlayout__column--text'> -->\r\n\t\t<p>Appuntamenti fissi che permettono ai lettori interessati di incontrarsi, scoprire nuove letture, approfondirne altre, conoscere nuovi autori. Ogni mese un libro viene letto in privato e poi condiviso per approfondirne insieme i temi, dare voce ai propri punti di vista e scambiarli con gli altri. Sono al momento attivi il gruppo \u2018<span style=\"text-decoration: underline; color: #000000;\"><a style=\"text-decoration: underline; color: #000000;\" href=\"https:\/\/fquerini.fabricandum.com\/di-libro-in-libro\/\">Di libro in libro<\/a><\/span><span style=\"color: #000000;\">\u2019<\/span><span style=\"color: #000000;\"> e<\/span><span style=\"color: #000000;\"> \u2018<\/span><span style=\"text-decoration: underline; color: #000000;\"><a style=\"text-decoration: underline; color: #000000;\" href=\"https:\/\/fquerini.fabricandum.com\/scompaginati\/\">Scompaginati<\/a><\/span><span style=\"color: #000000;\">\u2019.<\/span><span style=\"text-decoration: underline; color: #000000;\"><br \/><\/span><span style=\"color: #000000;\">La partecipazione \u00e8 libera, gratuita e aperta a tutti.<br \/><\/span>Per maggiori informazioni: <span style=\"text-decoration: underline; color: #000000;\"><a style=\"text-decoration: underline; color: #000000;\" href=\"mailto:biblioteca@querinistampalia.org\">biblioteca@querinistampalia.org<\/a><\/span><\/p>\t\t<!-- <\/p> -->\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t    <\/div>\r\n    <div class=\"boxlayout__column boxlayout__columngallery flex-1\">\r\n        <div class=\"swiper swiper6a04920a95a49\">\r\n          <!-- Additional required wrapper -->\r\n          <div class=\"swiper-wrapper\">\r\n            <!-- Slides -->\r\n\r\n\t\t\t            <div class=\"swiper-slide\">\r\n\t\t\r\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fquerini.fabricandum.com\/wp-content\/uploads\/2023\/01\/Gruppi-di-lettura.jpg\">\r\n\t\t\t<\/div>\r\n\r\n\t\t\t          \r\n          <\/div>\r\n    \r\n          <!-- If we need navigation buttons -->\r\n          <div class=\"swiper-button-prev\"><\/div>\r\n          <div class=\"swiper-button-next\"><\/div>\r\n    \r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n\r\n\r\n  \r\n\t\r\n<div class=\"boxlayout\" style=\"\">\r\n    <div class=\"boxlayout__column boxlayout__columntext flex-2\">\r\n        <h3 class=\"boxlayout__column--title\">Visite guidate alla Biblioteca<\/h3>\r\n\t\t\r\n\t\t\t\t\t\r\n        <!-- <p class='boxlayout__column--text'> -->\r\n\t\t<p>Un incontro ravvicinato con le fonti, i documenti manoscritti e a stampa della Fondazione. Itinerari su misura, dedicati a temi specifici. Si svolgono su prenotazione, da effettuare con anticipo di almeno una settimana.<\/p><p>Per informazioni e prenotazioni: <span style=\"text-decoration: underline; color: #000000;\"><a style=\"color: #000000; text-decoration: underline;\" href=\"mailto:ticketmuseum@querinistampalia.org\">ticketmuseum@querinistampalia.org<\/a><\/span><\/p>\t\t<!-- <\/p> -->\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t    <\/div>\r\n    <div class=\"boxlayout__column boxlayout__columngallery flex-1\">\r\n        <div class=\"swiper swiper6a04920a95a49\">\r\n          <!-- Additional required wrapper -->\r\n          <div class=\"swiper-wrapper\">\r\n            <!-- Slides -->\r\n\r\n\t\t\t            <div class=\"swiper-slide\">\r\n\t\t\r\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fquerini.fabricandum.com\/wp-content\/uploads\/2023\/01\/Visite-guidate-alla-biblioteca.jpg\">\r\n\t\t\t<\/div>\r\n\r\n\t\t\t          \r\n          <\/div>\r\n    \r\n          <!-- If we need navigation buttons -->\r\n          <div class=\"swiper-button-prev\"><\/div>\r\n          <div class=\"swiper-button-next\"><\/div>\r\n    \r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n\r\n<script>\r\nvar sliderRandom = new Swiper('.swiper6a04920a95a49', {\r\n  \/\/ Optional parameters\r\n  direction: 'horizontal',\r\n  loop: false,\r\n  watchOverflow: true,\r\n  \/\/ Navigation arrows\r\n  navigation: {\r\n    nextEl: '.swiper-button-next',\r\n    prevEl: '.swiper-button-prev',\r\n  },\r\n});\r\n<\/script>\r\n\r\n\t\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4388cc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c4388cc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4efab74\" data-id=\"4efab74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16278aa elementor-widget elementor-widget-html\" data-id=\"16278aa\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"events\">\r\n  <div class=\"events__column events-bottom-col box-bottom-half-size contrastable contrasted\" style=\"background: linear-gradient(0deg, rgba(0, 0, 0, 0.4), rgba(0, 0, 0, 0.4)), url('\/wp-content\/uploads\/2023\/01\/La_nostra_caffetteria.jpg'); position: relative;\">  \r\n   <h3 class=\"events__column--title\">Caffetteria: una pausa a regola d'arte<\/h3>\r\n   \r\n   <a href=\"\/caffetteria\/\" class=\"boxlayout__column--button\" style=\"color: white;\">\r\n     <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n     width=\"34\" height=\"34\" viewBox=\"0 0 34 34\" fill=\"none\">\r\n     <circle cx=\"17\" cy=\"17\" r=\"17\" fill=\"#BD995C\"><\/circle>\r\n     <path d=\"M25.8536 17.3536C26.0488 17.1583 26.0488 16.8417 25.8536 16.6464L22.6716 13.4645C22.4763 \r\n     13.2692 22.1597 13.2692 21.9645 13.4645C21.7692 13.6597 21.7692 13.9763 21.9645 14.1716L24.7929 \r\n     17L21.9645 19.8284C21.7692 20.0237 21.7692 20.3403 21.9645 20.5355C22.1597 20.7308 22.4763 \r\n     20.7308 22.6716 20.5355L25.8536 17.3536ZM8.5 17.5L25.5 17.5V16.5L8.5 16.5V17.5Z\" fill=\"#000\">\r\n    <\/path><\/svg>\r\n    <\/a>\r\n    \r\n  <\/div>\r\n  \r\n      <div class=\"events__column events-bottom-col box-bottom-half-size contrastable contrasted\" style=\"background: linear-gradient(0deg, rgba(0, 0, 0, 0.4), rgba(0, 0, 0, 0.4)), url('\/wp-content\/uploads\/2023\/01\/Le_meraviglie_del_bookshop.jpg'); position: relative;\">  \r\n   <h3 class=\"events__column--title\">Bookshop: trova l'ispirazione, con stile<\/h3>\r\n   \r\n   <a href=\"\/bookshop\/\" class=\"boxlayout__column--button\" style=\"color: white;\">\r\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\r\n     width=\"34\" height=\"34\" viewBox=\"0 0 34 34\" fill=\"none\">\r\n     <circle cx=\"17\" cy=\"17\" r=\"17\" fill=\"#BD995C\"><\/circle>\r\n     <path d=\"M25.8536 17.3536C26.0488 17.1583 26.0488 16.8417 25.8536 16.6464L22.6716 13.4645C22.4763 \r\n     13.2692 22.1597 13.2692 21.9645 13.4645C21.7692 13.6597 21.7692 13.9763 21.9645 14.1716L24.7929 \r\n     17L21.9645 19.8284C21.7692 20.0237 21.7692 20.3403 21.9645 20.5355C22.1597 20.7308 22.4763 \r\n     20.7308 22.6716 20.5355L25.8536 17.3536ZM8.5 17.5L25.5 17.5V16.5L8.5 16.5V17.5Z\" fill=\"#000\">\r\n    <\/path><\/svg>\r\n    <\/a>\r\n    \r\n  <\/div>\r\n<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95696ab elementor-section-height-min-height elementor-section-items-top help-section help-section-visita contrastable elementor-section-boxed elementor-section-height-default\" data-id=\"95696ab\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c1839b1\" data-id=\"c1839b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b66969c elementor-widget elementor-widget-heading\" data-id=\"b66969c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vuoi saperne di pi\u00f9?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db606f5 elementor-widget elementor-widget-text-editor\" data-id=\"db606f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Scrivici per maggiori informazioni<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7bf9a22\" data-id=\"7bf9a22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e58b148 elementor-widget elementor-widget-html\" data-id=\"e58b148\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"\/contattaci#biblioteca\" class=\"arrow-btn\">\r\n    CONTATTACI <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewBox=\"0 0 34 34\" fill=\"none\"><circle cx=\"17\" cy=\"17\" r=\"17\" fill=\"#000\"><\/circle><path d=\"M25.8536 17.3536C26.0488 17.1583 26.0488 16.8417 25.8536 16.6464L22.6716 13.4645C22.4763 13.2692 22.1597 13.2692 21.9645 13.4645C21.7692 13.6597 21.7692 13.9763 21.9645 14.1716L24.7929 17L21.9645 19.8284C21.7692 20.0237 21.7692 20.3403 21.9645 20.5355C22.1597 20.7308 22.4763 20.7308 22.6716 20.5355L25.8536 17.3536ZM8.5 17.5L25.5 17.5V16.5L8.5 16.5V17.5Z\" fill=\"#BD995C\"><\/path><\/svg>\r\n<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Biblioteca della Querini La formazione \u00e8 il nostro investimento La Biblioteca \u00e8 di carattere generale, conserva e mette a disposizione circa 400.000 volumi, tra opere antiche e libri moderni, ed \u00e8 considerata, da pi\u00f9 di 150 anni, la &#8216;biblioteca dei veneziani&#8217;. Aperta anche nei giorni festivi, vi possono accedere gratuitamente tutti coloro che hanno [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1522","page","type-page","status-publish","hentry"],"acf":[],"rankMath":{"parentDomain":"fquerini.fabricandum.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"L&#039;immagine in evidenza dovrebbe essere di almeno 200 x 200 pixel per essere ripresa da Facebook e altri siti di social media.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"biblioteca","permalinkFormat":"https:\/\/fquerini.fabricandum.com\/it\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/fquerini.fabricandum.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"Biblioteca - Fondazione Querini Stampalia","description":"La Biblioteca \u00e8 di carattere generale. Aperta anche nei giorni festivi, vi si accede gratuitamente con tessera.","focusKeywords":"biblioteca,tessera","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"nome utente","primaryTerm":0,"authorName":"milos.lukic@fabrico.digital","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":false},"homeUrl":"https:\/\/fquerini.fabricandum.com\/it\/","objectID":1522,"objectType":"post","locale":"it","localeFull":"it_IT","overlayImages":{"play":{"name":"Icona di riproduzione","url":"https:\/\/fquerini.fabricandum.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/home\/fquerini\/webapps\/fquerini\/web\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icona GIF","url":"https:\/\/fquerini.fabricandum.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/home\/fquerini\/webapps\/fquerini\/web\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/fquerini.fabricandum.com\/wp-content\/uploads\/2023\/05\/Q_social_share@2x.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Ffquerini.fabricandum.com%2Fit%2F&r=https%3A%2F%2Ffquerini.fabricandum.com%2Fit%2Fwp-json%2Fwp%2Fv2%2Fpages%2F1522%3Fnonce%3Dbed191efaa","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/fquerini.fabricandum.com\/wp-content\/uploads\/2023\/01\/Union.svg","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Aggiorna","trendsPreviewImage":"https:\/\/fquerini.fabricandum.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/fquerini.fabricandum.com\/it\/wp-json\/wp\/v2\/pages\/1522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fquerini.fabricandum.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fquerini.fabricandum.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fquerini.fabricandum.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fquerini.fabricandum.com\/it\/wp-json\/wp\/v2\/comments?post=1522"}],"version-history":[{"count":398,"href":"https:\/\/fquerini.fabricandum.com\/it\/wp-json\/wp\/v2\/pages\/1522\/revisions"}],"predecessor-version":[{"id":15581,"href":"https:\/\/fquerini.fabricandum.com\/it\/wp-json\/wp\/v2\/pages\/1522\/revisions\/15581"}],"wp:attachment":[{"href":"https:\/\/fquerini.fabricandum.com\/it\/wp-json\/wp\/v2\/media?parent=1522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}